{"id":206,"count":20,"description":"","link":"https:\/\/wormwheelgear.top\/th\/tag\/conveyor-top-chain-china\/","name":"\u0e2a\u0e32\u0e22\u0e1e\u0e32\u0e19\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07\u0e41\u0e1a\u0e1a\u0e42\u0e0b\u0e48\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19","slug":"conveyor-top-chain-china","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/th\/wp-json\/wp\/v2\/tags\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/th\/wp-json\/wp\/v2\/posts?tags=206"}],"curies":[{"name":"\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e1e\u0e35","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}