{"id":265,"count":4,"description":"","link":"https:\/\/wormwheelgear.top\/sv\/tag\/roller-chain-sprocket-plastic\/","name":"Rullkedjedrev Plast","slug":"roller-chain-sprocket-plastic","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/sv\/wp-json\/wp\/v2\/tags\/265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/sv\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/sv\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/sv\/wp-json\/wp\/v2\/posts?tags=265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}