{"id":1478,"count":1,"description":"","link":"https:\/\/wormwheelgear.top\/sv\/tag\/roller-chain-lube\/","name":"Roller Chain Lube","slug":"roller-chain-lube","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/sv\/wp-json\/wp\/v2\/tags\/1478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/sv\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/sv\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/sv\/wp-json\/wp\/v2\/posts?tags=1478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}