{"id":12,"count":4,"description":"","link":"https:\/\/wormwheelgear.top\/sr\/tag\/helical-gear-tooth\/","name":"helical gear tooth","slug":"helical-gear-tooth","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/sr\/wp-json\/wp\/v2\/tags\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/sr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/sr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/sr\/wp-json\/wp\/v2\/posts?tags=12"}],"curies":[{"name":"\u0412\u041f","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}