{"id":577,"count":49,"description":"","link":"https:\/\/wormwheelgear.top\/sk\/tag\/machinery\/","name":"stroje","slug":"machinery","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/tags\/577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/posts?tags=577"}],"curies":[{"name":"pracovn\u00fd list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}