{"id":39,"count":41,"description":"","link":"https:\/\/wormwheelgear.top\/sk\/tag\/chain-china\/","name":"Re\u0165az \u010c\u00edna","slug":"chain-china","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/tags\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/posts?tags=39"}],"curies":[{"name":"pracovn\u00fd list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}