{"id":130,"count":31,"description":"","link":"https:\/\/wormwheelgear.top\/sk\/tag\/sprocket-price\/","name":"cena ozuben\u00e9ho kolesa","slug":"sprocket-price","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/tags\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/sk\/wp-json\/wp\/v2\/posts?tags=130"}],"curies":[{"name":"pracovn\u00fd list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}