{"id":3408,"count":26,"description":"","link":"https:\/\/wormwheelgear.top\/ru\/tag\/crown-pinion-gear-wheel\/","name":"\u043a\u043e\u0440\u043e\u043d\u0447\u0430\u0442\u043e\u0435 \u0432\u0435\u0434\u0443\u0449\u0435\u0435 \u0437\u0443\u0431\u0447\u0430\u0442\u043e\u0435 \u043a\u043e\u043b\u0435\u0441\u043e","slug":"crown-pinion-gear-wheel","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/ru\/wp-json\/wp\/v2\/tags\/3408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/ru\/wp-json\/wp\/v2\/posts?tags=3408"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}