{"id":124,"count":11,"description":"","link":"https:\/\/wormwheelgear.top\/id\/tag\/roller-chain-conveyor\/","name":"konveyor rantai rol","slug":"roller-chain-conveyor","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/id\/wp-json\/wp\/v2\/tags\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/id\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/id\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/id\/wp-json\/wp\/v2\/posts?tags=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}