{"id":2121,"count":10,"description":"","link":"https:\/\/wormwheelgear.top\/fr\/tag\/helical-bevel-gear-reducer\/","name":"r\u00e9ducteur \u00e0 engrenages coniques h\u00e9lico\u00efdaux","slug":"helical-bevel-gear-reducer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/fr\/wp-json\/wp\/v2\/tags\/2121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/fr\/wp-json\/wp\/v2\/posts?tags=2121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}