{"id":2019,"count":154,"description":"","link":"https:\/\/wormwheelgear.top\/et\/tag\/spur-gear\/","name":"hammasratas","slug":"spur-gear","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/et\/wp-json\/wp\/v2\/tags\/2019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/et\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/et\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/et\/wp-json\/wp\/v2\/posts?tags=2019"}],"curies":[{"name":"t\u00f6\u00f6leht","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}