{"id":4590,"count":1,"description":"","link":"https:\/\/wormwheelgear.top\/de\/tag\/hydraulic-transmission\/","name":"hydraulic transmission","slug":"hydraulic-transmission","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wormwheelgear.top\/de\/wp-json\/wp\/v2\/tags\/4590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormwheelgear.top\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormwheelgear.top\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormwheelgear.top\/de\/wp-json\/wp\/v2\/posts?tags=4590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}